{"id":1999,"date":"2024-08-29T11:42:05","date_gmt":"2024-08-29T09:42:05","guid":{"rendered":"https:\/\/www.museeduvin-valais.ch\/expositions-passees\/mes-4-ceps-guide-du-petit-vigneron\/"},"modified":"2024-10-17T11:34:33","modified_gmt":"2024-10-17T09:34:33","slug":"in-erwartung-meiner-vier-rebstoecke","status":"publish","type":"page","link":"https:\/\/www.museeduvin-valais.ch\/de\/ausstellungen\/vergangene-ausstellungen\/in-erwartung-meiner-vier-rebstoecke\/","title":{"rendered":"In Erwartung meiner vier Rebst\u00f6cke"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":1915,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template\/left-navigation.php","meta":{"_acf_changed":false},"class_list":["post-1999","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>In Erwartung meiner vier Rebst\u00f6cke - Walliser Reb- und Weinmuseum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.museeduvin-valais.ch\/de\/ausstellungen\/vergangene-ausstellungen\/in-erwartung-meiner-vier-rebstoecke\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In Erwartung meiner vier Rebst\u00f6cke - Walliser Reb- und Weinmuseum\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.museeduvin-valais.ch\/de\/ausstellungen\/vergangene-ausstellungen\/in-erwartung-meiner-vier-rebstoecke\/\" \/>\n<meta property=\"og:site_name\" content=\"Walliser Reb- und Weinmuseum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/museeduvin.weinmuseum\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-17T09:34:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.museeduvin-valais.ch\\\/de\\\/ausstellungen\\\/vergangene-ausstellungen\\\/in-erwartung-meiner-vier-rebstoecke\\\/\",\"url\":\"https:\\\/\\\/www.museeduvin-valais.ch\\\/de\\\/ausstellungen\\\/vergangene-ausstellungen\\\/in-erwartung-meiner-vier-rebstoecke\\\/\",\"name\":\"In Erwartung meiner vier Rebst\u00f6cke - Walliser Reb- und Weinmuseum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.museeduvin-valais.ch\\\/de\\\/#website\"},\"datePublished\":\"2024-08-29T09:42:05+00:00\",\"dateModified\":\"2024-10-17T09:34:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.museeduvin-valais.ch\\\/de\\\/ausstellungen\\\/vergangene-ausstellungen\\\/in-erwartung-meiner-vier-rebstoecke\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.museeduvin-valais.ch\\\/de\\\/ausstellungen\\\/vergangene-ausstellungen\\\/in-erwartung-meiner-vier-rebstoecke\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.museeduvin-valais.ch\\\/de\\\/ausstellungen\\\/vergangene-ausstellungen\\\/in-erwartung-meiner-vier-rebstoecke\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.museeduvin-valais.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ausstellungen\",\"item\":\"https:\\\/\\\/www.museeduvin-valais.ch\\\/de\\\/ausstellungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vergangene Ausstellungen\",\"item\":\"https:\\\/\\\/www.museeduvin-valais.ch\\\/de\\\/ausstellungen\\\/vergangene-ausstellungen\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"In Erwartung meiner vier Rebst\u00f6cke\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.museeduvin-valais.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.museeduvin-valais.ch\\\/de\\\/\",\"name\":\"Mus\u00e9e Valaisan de la vigne et du vin\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.museeduvin-valais.ch\\\/de\\\/#organization\"},\"alternateName\":\"Mus\u00e9e du vin\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.museeduvin-valais.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.museeduvin-valais.ch\\\/de\\\/#organization\",\"name\":\"Mus\u00e9e Valaisan de la vigne et du vin\",\"url\":\"https:\\\/\\\/www.museeduvin-valais.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.museeduvin-valais.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.museeduvin-valais.ch\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-mb.svg\",\"contentUrl\":\"https:\\\/\\\/www.museeduvin-valais.ch\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/logo-mb.svg\",\"width\":1,\"height\":1,\"caption\":\"Mus\u00e9e Valaisan de la vigne et du vin\"},\"image\":{\"@id\":\"https:\\\/\\\/www.museeduvin-valais.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/museeduvin.weinmuseum\",\"https:\\\/\\\/www.instagram.com\\\/museeduvinvalais\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"In Erwartung meiner vier Rebst\u00f6cke - Walliser Reb- und Weinmuseum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.museeduvin-valais.ch\/de\/ausstellungen\/vergangene-ausstellungen\/in-erwartung-meiner-vier-rebstoecke\/","og_locale":"de_DE","og_type":"article","og_title":"In Erwartung meiner vier Rebst\u00f6cke - Walliser Reb- und Weinmuseum","og_url":"https:\/\/www.museeduvin-valais.ch\/de\/ausstellungen\/vergangene-ausstellungen\/in-erwartung-meiner-vier-rebstoecke\/","og_site_name":"Walliser Reb- und Weinmuseum","article_publisher":"https:\/\/www.facebook.com\/museeduvin.weinmuseum","article_modified_time":"2024-10-17T09:34:33+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.museeduvin-valais.ch\/de\/ausstellungen\/vergangene-ausstellungen\/in-erwartung-meiner-vier-rebstoecke\/","url":"https:\/\/www.museeduvin-valais.ch\/de\/ausstellungen\/vergangene-ausstellungen\/in-erwartung-meiner-vier-rebstoecke\/","name":"In Erwartung meiner vier Rebst\u00f6cke - Walliser Reb- und Weinmuseum","isPartOf":{"@id":"https:\/\/www.museeduvin-valais.ch\/de\/#website"},"datePublished":"2024-08-29T09:42:05+00:00","dateModified":"2024-10-17T09:34:33+00:00","breadcrumb":{"@id":"https:\/\/www.museeduvin-valais.ch\/de\/ausstellungen\/vergangene-ausstellungen\/in-erwartung-meiner-vier-rebstoecke\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.museeduvin-valais.ch\/de\/ausstellungen\/vergangene-ausstellungen\/in-erwartung-meiner-vier-rebstoecke\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.museeduvin-valais.ch\/de\/ausstellungen\/vergangene-ausstellungen\/in-erwartung-meiner-vier-rebstoecke\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.museeduvin-valais.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Ausstellungen","item":"https:\/\/www.museeduvin-valais.ch\/de\/ausstellungen\/"},{"@type":"ListItem","position":3,"name":"Vergangene Ausstellungen","item":"https:\/\/www.museeduvin-valais.ch\/de\/ausstellungen\/vergangene-ausstellungen\/"},{"@type":"ListItem","position":4,"name":"In Erwartung meiner vier Rebst\u00f6cke"}]},{"@type":"WebSite","@id":"https:\/\/www.museeduvin-valais.ch\/de\/#website","url":"https:\/\/www.museeduvin-valais.ch\/de\/","name":"Mus\u00e9e Valaisan de la vigne et du vin","description":"","publisher":{"@id":"https:\/\/www.museeduvin-valais.ch\/de\/#organization"},"alternateName":"Mus\u00e9e du vin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.museeduvin-valais.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.museeduvin-valais.ch\/de\/#organization","name":"Mus\u00e9e Valaisan de la vigne et du vin","url":"https:\/\/www.museeduvin-valais.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.museeduvin-valais.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.museeduvin-valais.ch\/wp-content\/uploads\/2024\/11\/logo-mb.svg","contentUrl":"https:\/\/www.museeduvin-valais.ch\/wp-content\/uploads\/2024\/11\/logo-mb.svg","width":1,"height":1,"caption":"Mus\u00e9e Valaisan de la vigne et du vin"},"image":{"@id":"https:\/\/www.museeduvin-valais.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/museeduvin.weinmuseum","https:\/\/www.instagram.com\/museeduvinvalais"]}]}},"_links":{"self":[{"href":"https:\/\/www.museeduvin-valais.ch\/de\/wp-json\/wp\/v2\/pages\/1999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.museeduvin-valais.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.museeduvin-valais.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.museeduvin-valais.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.museeduvin-valais.ch\/de\/wp-json\/wp\/v2\/comments?post=1999"}],"version-history":[{"count":2,"href":"https:\/\/www.museeduvin-valais.ch\/de\/wp-json\/wp\/v2\/pages\/1999\/revisions"}],"predecessor-version":[{"id":2003,"href":"https:\/\/www.museeduvin-valais.ch\/de\/wp-json\/wp\/v2\/pages\/1999\/revisions\/2003"}],"up":[{"embeddable":true,"href":"https:\/\/www.museeduvin-valais.ch\/de\/wp-json\/wp\/v2\/pages\/1915"}],"wp:attachment":[{"href":"https:\/\/www.museeduvin-valais.ch\/de\/wp-json\/wp\/v2\/media?parent=1999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}